{"id":506,"date":"2026-03-31T16:26:21","date_gmt":"2026-03-31T16:26:21","guid":{"rendered":""},"modified":"2026-03-31T16:26:21","modified_gmt":"2026-03-31T16:26:21","slug":"politica-de-cookies-ue-ca","status":"publish","type":"page","link":"https:\/\/giteb.com\/ca\/politica-de-cookies-ue-ca\/","title":{"rendered":"Pol\u00edtica de cookies (UE)"},"content":{"rendered":"\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Aquesta pol\u00edtica de galetes es va actualitzar per \u00faltima vegada el 26 de novembre de 2025 i s\u2019aplica a ciutadans i residents legals permanents de l&#8217;Espai Econ\u00f2mic Europeu i Su\u00efssa.<\/i><br><\/p><h2>1. Introducci\u00f3<\/h2><p>El nostre lloc web, <a href=\"https:\/\/giteb.com\/ca\/\">https:\/\/giteb.com\/ca\/<\/a> (d&#8217;ara endavant  &#8220;el lloc web&#8221;) utilitza galetes i altres tecnologies relacionades (per comoditat, totes les tecnologies es denominen  &#8220;galetes&#8221;). Les galetes tamb\u00e9 s\u00f3n col\u00b7locades per tercers que hem contractat. En el document seg\u00fcent us informem sobre l&#8217;\u00fas de les galetes al nostre lloc web.<\/p><h2>2. Qu\u00e8 s\u00f3n les galetes?<\/h2><p>Una galeta \u00e9s un fitxer petit i senzill que s&#8217;envia juntament amb p\u00e0gines d&#8217;aquest lloc web i que el vostre navegador emmagatzema al disc dur de l&#8217;ordinador o un altre dispositiu. La informaci\u00f3 emmagatzemada en ell es pot tornar als nostres servidors o als servidors dels tercers corresponents durant una visita posterior.<\/p><h2>3. Qu\u00e8 s\u00f3n els scripts?<\/h2><p>Un script \u00e9s una pe\u00e7a de codi de programari que s&#8217;utilitza per a que el nostre web funcioni correctament i interactivament. Aquest codi s&#8217;executa al nostre servidor o al vostre dispositiu.<\/p><h2>4. Qu\u00e8 \u00e9s una balisa web?<\/h2><p>Una balisa web (o una etiqueta de p\u00edxel) \u00e9s una petita i invisible pe\u00e7a de text o imatge en un lloc web que s&#8217;utilitza per controlar el tr\u00e0nsit d&#8217;un lloc web. Per fer-ho, s&#8217;emmagatzemen diverses dades utilitzant balises web.<\/p><h2>5. Galetes<\/h2><p class=\"cmplz-subtitle\">5.1 Galetes t\u00e8cniques o funcionals<\/p><p>Algunes galetes asseguren que certes parts del lloc web funcionen correctament i que les prefer\u00e8ncies dels usuaris segueixin sent conegudes. Utilitzant galetes funcionals, us facilitem que visiteu el nostre lloc web. D&#8217;aquesta manera, no cal que introdu\u00efu repetidament la mateixa informaci\u00f3 quan visiteu el nostre lloc web i, per exemple, els elements romanen al carret\u00f3 de la compra fins que h\u00e0giu pagat. Podem posar aquestes galetes sense el vostre consentiment.<\/p><p class=\"cmplz-subtitle\">5.2 Cookies d&#039;estad\u00edstica<\/p><p>Utilitzem cookies anal\u00edtiques per optimitzar l&#8217;experi\u00e8ncia del lloc web per als nostres usuaris. Amb aquestes cookies anal\u00edtiques obtenim informaci\u00f3 sobre l&#8217;\u00fas del nostre lloc web.&nbsp;Us demanem perm\u00eds per col\u00b7locar cookies d&#8217;estad\u00edstiques.<\/p><p class=\"cmplz-subtitle\">5.3 Cookies de m\u00e0rqueting\/seguiment<\/p><p>Les galetes de m\u00e0rqueting\/seguiment s\u00f3n galetes o qualsevol altra forma d&#8217;emmagatzematge local que s&#8217;utilitzen per crear perfils d&#8217;usuari per mostrar publicitat o per fer un seguiment de l&#8217;usuari en aquest lloc web o en diversos llocs web amb finalitats de m\u00e0rqueting similars.<\/p><p class=\"cmplz-subtitle\">5.4 Mitjans socials<\/p><p>Al nostre lloc web, hem incl\u00f2s contingut de Instagram per promocionar p\u00e0gines web (per exemple, &#8220;m&#8217;agrada&#8221;, &#8220;pin&#8221;) o compartir (per exemple, &#8220;tuitejar&#8221;) a xarxes socials com Instagram. Aquest contingut est\u00e0 incrustat amb codi derivat de Instagram i col\u00b7loca galetes. Aquest contingut pot emmagatzemar i processar certa informaci\u00f3 per a publicitat personalitzada.<\/p><p>Llegiu, si us plau, la pol\u00edtica de privacitat d&#8217;aquestes xarxes socials (que poden canviar regularment) per entendre qu\u00e8 fan amb les vostres dades personals processades utilitzant aquestes cookies. Les dades recuperades s\u00f3n anonimitzades el m\u00e0xim possible. Instagram es troba als Estats Units.<\/p><h2>6. Galetes col\u00b7locades<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Diversos<\/h3>\n\t\t<p>Finalitat pendent d&#8217;investigaci\u00f3<\/p>\n\t\t<label for=\"cmplz_service_diversos\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service diversos<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_diversos\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"diversos\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>L&#8217;intercanvi de dades est\u00e0 pendent d&#8217;investigaci\u00f3<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalitat pendent d&#8217;investigaci\u00f3<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ate-maiya-info<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">gt-current-screen-giteb.com<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">WP_PREFERENCES_USER_1<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">uagSvgConfirmation<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_1<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ate-maiya-info_38386339-3363-5933-b732-363233383264<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">spectraCopyPasteStyles<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wpml-available-translators-notice-dismissed<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">sidebar-collapsed<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">customizerVisitCount<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">History.store<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wpEmojiSettingsSupports<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_gid<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-1<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-time-1<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_ga<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wp-wpml_current_admin_language_d41d8cd98f00b204e9800998ecf8427e<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">PHPSESSID<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wp-wpml_current_language<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_ga_23XZJTLSDV<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wordpress_test_cookie<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wordpress_logged_in_c34b7b8b252f057ef295be8ac9fd8c1a<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">NFWSESSID<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_cookie_data<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consentiment<\/h2><p>Quan visiteu el nostre lloc web per primera vegada, us mostrarem un missatge emergent amb una explicaci\u00f3 sobre les cookies. Tan bon punt com feu clic a &#8220;Guardar preferencias&#8221;, ens consentiu a utilitzar les categories de cookies i extensions que heu seleccionat al missatge emergent, tal i com es descriu en aquesta Pol\u00edtica de cookies. Podeu desactivar l\u2019\u00fas de cookies a trav\u00e9s del vostre navegador, per\u00f2 tingueu en compte que pot ser que el nostre lloc web ja no funcioni correctament.<\/p><p class=\"cmplz-subtitle\">7.1 Gestioneu la vostra configuraci\u00f3 de consentiment<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Heu carregat la Pol\u00edtica de galetes sense suport javascript.&nbsp;A AMP, podeu utilitzar el bot\u00f3 de gesti\u00f3 del consentiment a la part inferior de la p\u00e0gina.<\/div><div id=\"cmplz-manage-consent-container\" name=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Activaci\u00f3 \/ desactivaci\u00f3 i eliminaci\u00f3 de galetes<\/h2><p>Podeu utilitzar el navegador per a esborrar les cookies autom\u00e0ticament o manualment. A m\u00e9s, podeu especificar que determinades cookies no siguin col\u00b7locades. Una altra opci\u00f3 \u00e9s canviar les prefer\u00e8ncies del vostre navegador per a rebre un missatge cada cop que una cookie \u00e9s col\u00b7locada. Per a m\u00e9s informaci\u00f3, podeu consultar les instruccions a l&#8217;Ajuda del vostre navegador.<\/p><p>Tingueu en compte que el nostre lloc web pot no funcionar correctament si totes les galetes estan desactivades. Si suprimiu les galetes del navegador, se&#8217;n crearan de noves despr\u00e9s del vostre consentiment quan torneu a visitar els nostres llocs web.<\/p><h2>9. Els vostres drets respecte de les dades personals<\/h2><p>Teniu els drets seg\u00fcents respecte a les vostres dades personals:<\/p><ul>\n                    <li>Teniu dret a saber per qu\u00e8 es necessiten les vostres dades personals, qu\u00e8 hi passar\u00e0 i quant de temps es conservaran.<\/li>\n                    <li>Dret d&#8217;acc\u00e9s: teniu dret a accedir a les vostres dades personals que ens s\u00f3n conegudes.<\/li>\n                    <li>Dret de rectificaci\u00f3: teniu dret a completar, corregir, suprimir o bloquejar les vostres dades personals sempre que ho desitgeu.<\/li>\n                    <li>Si ens doneu el consentiment per processar les seves dades, teniu el dret de revocar aquest consentiment i de suprimir les vostres dades personals.<\/li>\n                    <li>Dret de transferir les vostres dades: teniu el dret de sol\u00b7licitar totes les dades personals del controlador i transferir-les en la seva totalitat a un altre controlador.<\/li>\n                    <li>Dret a l&#8217;oposici\u00f3: podeu oposar-vos al processament de les vostres dades. Complim amb aix\u00f2, tret que hi hagi motius justificats per al processament.<\/li>\n                <\/ul><p>Per exercir aquests drets, poseu-vos en contacte amb nosaltres. Consulteu les dades de contacte a la part inferior d&#8217;aquesta Pol\u00edtica de cookies. Si teniu una queixa sobre com gestionem les vostres dades, ens agradaria escoltar-vos, per\u00f2 tamb\u00e9 teniu el dret de presentar una reclamaci\u00f3 a l&#8217;autoritat de supervisi\u00f3 (l&#8217;Ag\u00e8ncia de Protecci\u00f3 de Dades).<\/p><h2>10. Detalls de contacte<\/h2><p>Per a preguntes i\/o comentaris sobre la nostra Pol\u00edtica de galetes i aquesta declaraci\u00f3, poseu-vos en contacte amb nosaltres mitjan\u00e7ant les seg\u00fcents dades de contacte:<\/p><p><span class=\"cmplz-contact-organisation\">Gesti\u00f3 T\u00e8cnica d\u2019Edificaci\u00f3 i Rehabilitaci\u00f3, S.L.<\/span><br>\n                      <span class=\"cmplz-contact-address\">Pau Alsina, 36, local 5 &#8211; 08025 Barcelona<\/span><br>\n                      <span class=\"cmplz-contact-country\">Espanya<\/span><br>\n                      <span class=\"cmplz-contact-domain\">Lloc web: <a href=\"https:\/\/giteb.com\/ca\/\">https:\/\/giteb.com\/ca\/<\/a><\/span><br>\n                      <span class=\"cmplz-contact-email\">Correu electr\u00f2nic: <span class=\"cmplz-obfuscate\">&#103;i&#116;&#101;&#098;@<span class=\"cmplz-fmail-domain\">&#101;&#120;&#046;&#099;&#111;&#109;<\/span>&#103;&#105;&#116;e&#098;.&#099;o&#109;<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\">Phone number: 93 219 09 83<\/span><\/p><p>Aquesta pol\u00edtica de galetes s&#8217;ha sincronitzat amb <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> el 2 de mar\u00e7 de 2026.<\/p><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-506","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"david@kreamedia.com","author_link":"https:\/\/giteb.com\/ca\/author\/davidkreamedia-com\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/giteb.com\/ca\/wp-json\/wp\/v2\/pages\/506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giteb.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/giteb.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/giteb.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/giteb.com\/ca\/wp-json\/wp\/v2\/comments?post=506"}],"version-history":[{"count":0,"href":"https:\/\/giteb.com\/ca\/wp-json\/wp\/v2\/pages\/506\/revisions"}],"wp:attachment":[{"href":"https:\/\/giteb.com\/ca\/wp-json\/wp\/v2\/media?parent=506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}